{"id":2616,"date":"2022-12-21T19:35:52","date_gmt":"2022-12-21T18:35:52","guid":{"rendered":"https:\/\/www.residenciajoviar.com\/?p=2616"},"modified":"2022-12-26T19:40:42","modified_gmt":"2022-12-26T18:40:42","slug":"preparant-el-nadal","status":"publish","type":"post","link":"https:\/\/www.residenciajoviar.com\/es\/preparant-el-nadal\/","title":{"rendered":"Preparant el Nadal"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><a href=\"https:\/\/www.instagram.com\/residenciajoviar\/\"><\/a><\/h2>\n\n\n\n<p>El Centre Residencial Joviar es prepara pel Nadal amb la decoraci\u00f3 de diferents espais i amb l&#8217;organitzaci\u00f3 de diferents activitats i tallers, com el de preparaci\u00f3 de postals. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"2624\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-2-1024x1024.png\" alt=\"\" class=\"wp-image-2624\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-2-1024x1024.png 1024w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-2-980x980.png 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-2-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"2622\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-3-1024x1024.png\" alt=\"\" class=\"wp-image-2622\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-3-1024x1024.png 1024w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-3-980x980.png 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-3-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"2620\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-4-1024x1024.png\" alt=\"\" class=\"wp-image-2620\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-4-1024x1024.png 1024w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-4-980x980.png 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-4-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"2628\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-5-1024x1024.png\" alt=\"\" class=\"wp-image-2628\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-5-1024x1024.png 1024w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-5-980x980.png 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-5-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"2626\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-1024x1024.png\" alt=\"\" class=\"wp-image-2626\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-1024x1024.png 1024w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-980x980.png 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Postal-Nadal-480x480.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2630\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Copia-de-IMG20221214123709-1-1024x768.jpg\" alt=\"\" class=\"wp-image-2630\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Copia-de-IMG20221214123709-1-980x735.jpg 980w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/Copia-de-IMG20221214123709-1-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"777\" height=\"647\" data-id=\"2634\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png\" alt=\"\" class=\"wp-image-2634\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png 777w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08-480x400.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 777px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"739\" height=\"630\" data-id=\"2632\" src=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h38_53.png\" alt=\"\" class=\"wp-image-2632\" srcset=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h38_53.png 739w, https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h38_53-480x409.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 739px, 100vw\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El Centre Residencial Joviar es prepara pel Nadal amb la decoraci\u00f3 de diferents espais i amb l&#8217;organitzaci\u00f3 de diferents activitats i tallers, com el de preparaci\u00f3 de postals.<\/p>\n","protected":false},"author":2,"featured_media":2634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4],"tags":[246,42,245],"class_list":["post-2616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies","tag-decoracio","tag-nadal","tag-nadal-a-joviar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions<\/title>\n<meta name=\"description\" content=\"Preparant el Nadal al Centre Residencial Joviar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions\" \/>\n<meta property=\"og:description\" content=\"Preparant el Nadal al Centre Residencial Joviar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/\" \/>\n<meta property=\"og:site_name\" content=\"RESID\u00c8NCIA JOVIAR - Centre lliure de contencions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/residenciajoviar\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T18:35:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-26T18:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"joviar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JoviarLleida\" \/>\n<meta name=\"twitter:site\" content=\"@JoviarLleida\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"joviar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/\"},\"author\":{\"name\":\"joviar\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/#\\\/schema\\\/person\\\/924a71fa2a3d57e4b46891a48f2d22a9\"},\"headline\":\"Preparant el Nadal\",\"datePublished\":\"2022-12-21T18:35:52+00:00\",\"dateModified\":\"2022-12-26T18:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/\"},\"wordCount\":32,\"image\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.residenciajoviar.com\\\/wp-content\\\/uploads\\\/2022-12-26_19h39_08.png\",\"keywords\":[\"Decoraci\u00f3\",\"nadal\",\"Nadal a Joviar\"],\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/\",\"url\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/\",\"name\":\"Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.residenciajoviar.com\\\/wp-content\\\/uploads\\\/2022-12-26_19h39_08.png\",\"datePublished\":\"2022-12-21T18:35:52+00:00\",\"dateModified\":\"2022-12-26T18:40:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/#\\\/schema\\\/person\\\/924a71fa2a3d57e4b46891a48f2d22a9\"},\"description\":\"Preparant el Nadal al Centre Residencial Joviar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.residenciajoviar.com\\\/wp-content\\\/uploads\\\/2022-12-26_19h39_08.png\",\"contentUrl\":\"https:\\\/\\\/www.residenciajoviar.com\\\/wp-content\\\/uploads\\\/2022-12-26_19h39_08.png\",\"width\":777,\"height\":647},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/preparant-el-nadal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.residenciajoviar.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparant el Nadal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/#website\",\"url\":\"https:\\\/\\\/www.residenciajoviar.com\\\/\",\"name\":\"RESID\u00c8NCIA JOVIAR - Centre lliure de contencions\",\"description\":\"Centre lliure de contencions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.residenciajoviar.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.residenciajoviar.com\\\/#\\\/schema\\\/person\\\/924a71fa2a3d57e4b46891a48f2d22a9\",\"name\":\"joviar\",\"url\":\"https:\\\/\\\/www.residenciajoviar.com\\\/es\\\/author\\\/joviar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions","description":"Preparant el Nadal al Centre Residencial Joviar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/","og_locale":"es_ES","og_type":"article","og_title":"Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions","og_description":"Preparant el Nadal al Centre Residencial Joviar","og_url":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/","og_site_name":"RESID\u00c8NCIA JOVIAR - Centre lliure de contencions","article_publisher":"https:\/\/www.facebook.com\/residenciajoviar\/","article_published_time":"2022-12-21T18:35:52+00:00","article_modified_time":"2022-12-26T18:40:42+00:00","og_image":[{"width":777,"height":647,"url":"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png","type":"image\/png"}],"author":"joviar","twitter_card":"summary_large_image","twitter_creator":"@JoviarLleida","twitter_site":"@JoviarLleida","twitter_misc":{"Escrito por":"joviar","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#article","isPartOf":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/"},"author":{"name":"joviar","@id":"https:\/\/www.residenciajoviar.com\/#\/schema\/person\/924a71fa2a3d57e4b46891a48f2d22a9"},"headline":"Preparant el Nadal","datePublished":"2022-12-21T18:35:52+00:00","dateModified":"2022-12-26T18:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/"},"wordCount":32,"image":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png","keywords":["Decoraci\u00f3","nadal","Nadal a Joviar"],"articleSection":["Not\u00edcies"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/","url":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/","name":"Preparant el Nadal - RESID\u00c8NCIA JOVIAR - Centre lliure de contencions","isPartOf":{"@id":"https:\/\/www.residenciajoviar.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#primaryimage"},"image":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png","datePublished":"2022-12-21T18:35:52+00:00","dateModified":"2022-12-26T18:40:42+00:00","author":{"@id":"https:\/\/www.residenciajoviar.com\/#\/schema\/person\/924a71fa2a3d57e4b46891a48f2d22a9"},"description":"Preparant el Nadal al Centre Residencial Joviar","breadcrumb":{"@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#primaryimage","url":"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png","contentUrl":"https:\/\/www.residenciajoviar.com\/wp-content\/uploads\/2022-12-26_19h39_08.png","width":777,"height":647},{"@type":"BreadcrumbList","@id":"https:\/\/www.residenciajoviar.com\/preparant-el-nadal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.residenciajoviar.com\/es\/"},{"@type":"ListItem","position":2,"name":"Preparant el Nadal"}]},{"@type":"WebSite","@id":"https:\/\/www.residenciajoviar.com\/#website","url":"https:\/\/www.residenciajoviar.com\/","name":"RESID\u00c8NCIA JOVIAR - Centre lliure de contencions","description":"Centre lliure de contencions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.residenciajoviar.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.residenciajoviar.com\/#\/schema\/person\/924a71fa2a3d57e4b46891a48f2d22a9","name":"joviar","url":"https:\/\/www.residenciajoviar.com\/es\/author\/joviar\/"}]}},"_links":{"self":[{"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/posts\/2616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/comments?post=2616"}],"version-history":[{"count":0,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/posts\/2616\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/media\/2634"}],"wp:attachment":[{"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/media?parent=2616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/categories?post=2616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.residenciajoviar.com\/es\/wp-json\/wp\/v2\/tags?post=2616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}